{"id":7040,"date":"2025-02-14T00:07:15","date_gmt":"2025-02-13T23:07:15","guid":{"rendered":"https:\/\/www.proselectint.com\/?p=7040"},"modified":"2025-07-03T15:22:09","modified_gmt":"2025-07-03T13:22:09","slug":"pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect","status":"publish","type":"post","link":"https:\/\/www.proselectint.com\/de_de\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/","title":{"rendered":"Liebe kennt keine Grenzen &#8211; Valentinstag bei PRO SELECT"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7040\" class=\"elementor elementor-7040\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9376e21 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"9376e21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a70b546 exad-glass-effect-no exad-sticky-section-no\" data-id=\"a70b546\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2884ae3b elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"2884ae3b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6d6f37d6 exad-glass-effect-no exad-sticky-section-no\" data-id=\"6d6f37d6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72ea2051 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"72ea2051\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Heute ist <strong>Valentinstag<\/strong> \u2013 ein Tag, an dem wir die Liebe in all ihren Formen feiern. Bei PRO SELECT steht der Valentinstag nicht nur f\u00fcr Blumen und Pralinen, sondern f\u00fcr die wahren Liebesgeschichten, die uns in unserer Arbeit jeden Tag ber\u00fchren. Es sind Geschichten von Mut, Hoffnung und der unersch\u00fctterlichen Kraft der Liebe, die keine Grenzen kennt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d601fd exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"4d601fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"992\" height=\"557\" src=\"https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942.png\" class=\"attachment-large size-large wp-image-7041\" alt=\"\" srcset=\"https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942.png 992w, https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942-300x168.png 300w, https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942-768x431.png 768w, https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942-18x10.png 18w\" sizes=\"(max-width: 992px) 100vw, 992px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fa891db exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"3fa891db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Liebe kennt keine Grenzen - aber sie braucht manchmal Unterst\u00fctzung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-509a5363 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"509a5363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PRO SELECT ist auf die Vermittlung von medizinischen Fachkr\u00e4ften aus Drittstaaten spezialisiert, die in Deutschland ihre Karriere fortsetzen und ein neues Leben beginnen m\u00f6chten. Doch hinter jeder Bewerbung, hinter jedem Lebenslauf stecken oft ganz pers\u00f6nliche Tr\u00e4ume \u2013 und manchmal sind es Tr\u00e4ume von zwei Menschen, die ihren Weg zusammen gehen wollen. Paare, die sich entscheiden, ihr Leben gemeinsam in einem neuen Land aufzubauen, bringen eine besondere Geschichte mit. F\u00fcr viele bedeutet der Schritt nach Deutschland nicht nur eine Karrierechance, sondern die Hoffnung auf ein neues Leben \u2013 gemeinsam, Hand in Hand.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a613ebe exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"a613ebe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.proselectint.com\/wp-content\/uploads\/elementor\/thumbs\/IMG_7677-r1f11mi3e632s7z2rlu10m7jvh0gnc22w0m0mmgrjk.jpeg\" title=\"IMG_7677\" alt=\"IMG_7677\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77c22669 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"77c22669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erfolgsgeschichten, die das Herz erw\u00e4rmern<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-262cde4c exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"262cde4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In den vergangenen Jahren haben wir es geschafft, zahlreiche Paare bei ihrem Weg nach Deutschland zu begleiten.<\/p><p>Wir erinnern uns an Paare, die wochenlang getrennt waren, weil sie auf ihre Visa warten mussten, oder an die emotionale Anspannung, wenn der Tag der Einreise n\u00e4her r\u00fcckte. Aber wir erinnern uns auch an die Freudentr\u00e4nen, die ersten Umarmungen in Deutschland und das unbeschreibliche Gef\u00fchl, wenn zwei Menschen endlich ihren neuen Lebensweg zusammen beginnen konnten.<\/p><p>Unsere Arbeit endet nicht mit der erfolgreichen Vermittlung \u2013 sie beginnt oft erst richtig, wenn wir sehen, wie diese Paare ihre ersten Schritte in einem neuen Kapitel ihres Lebens machen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bc21de exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"7bc21de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mehr als nur Jobvermittlung - wir schenken Perspektiven<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c1f27d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"4c1f27d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei PRO SELECT geht es nicht nur um die Suche nach einem passenden Arbeitgeber oder die Anerkennung von Qualifikationen. Es geht darum, Leben zu ver\u00e4ndern. Wir begleiten unsere Kandidaten durch jeden Schritt des Prozesses:<\/p><ul><li>Anerkennung ihrer Qualifikationen,<\/li><li>Suche nach passenden Arbeitgebern,<\/li><li>Unterst\u00fctzung bei Visumantr\u00e4gen und Botschaftsunterlagen,<\/li><li>Organisation der Einreise nach Deutschland,<\/li><li>Planung von Relocation-Services,<\/li><li>und stehen immer zur Seite \u2013 als Berater, Begleiter und oft auch als moralische St\u00fctze.<\/li><\/ul><p>Wir sind stolz darauf, in jedem Bereich zur Seite zu stehen, wo wir gebraucht werden \u2013 sei es beruflich, organisatorisch oder emotional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e783c7a exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"e783c7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.proselectint.com\/wp-content\/uploads\/elementor\/thumbs\/IMG_4432-r1f11lk97c1sgm0fx3feg4g3a353fmycjvyj5ci5ps.jpeg\" title=\"IMG_4432\" alt=\"IMG_4432\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcdb861 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"bcdb861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ein Valentinstag der besonderen Art<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-114245b exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"114245b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>An einem Tag wie heute erinnern wir uns daran, dass unsere Arbeit nicht nur Berufe vermittelt, sondern auch Leben ver\u00e4ndert. Besonders die Geschichten unserer Paare, die dank PRO SELECT einen neuen gemeinsamen Lebensabschnitt beginnen konnten, sind f\u00fcr uns ein Antrieb, weiterhin mit Hingabe und Leidenschaft zu arbeiten.<\/p><p>Wir bei PRO SELECT sind stolz darauf, Teil eurer Reise zu sein. Wir feiern nicht nur die beruflichen Erfolge, sondern auch die kleinen, stillen Momente: das Wiedersehen nach einer langen Trennung, das erste gemeinsame Zuhause in Deutschland, die Hoffnung, die in euren Augen leuchtet.<\/p><p>Das gesamte Team von PRO SELECT w\u00fcnscht allen Paaren, allen Kandidaten und allen, die an die Kraft der Liebe glauben, einen wundersch\u00f6nen Valentinstag voller Hoffnung, Gl\u00fcck und unvergesslicher Momente. allen Paaren, Kandidaten und Partnern einen wundersch\u00f6nen Valentinstag voller Liebe und Hoffnung auf die Zukunft!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcf92ca exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"bcf92ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47e22b1f elementor-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-button\" data-id=\"47e22b1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/www.proselectint.com\/de_de\/kontakt-kooperation\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256s111 248 248 248 248-111 248-248zm-448 0c0-110.5 89.5-200 200-200s200 89.5 200 200-89.5 200-200 200S56 366.5 56 256zm72 20v-40c0-6.6 5.4-12 12-12h116v-67c0-10.7 12.9-16 20.5-8.5l99 99c4.7 4.7 4.7 12.3 0 17l-99 99c-7.6 7.6-20.5 2.2-20.5-8.5v-67H140c-6.6 0-12-5.4-12-12z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt kontaktieren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0384d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default exad-glass-effect-no exad-sticky-section-no\" data-id=\"d0384d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-297e9aa exad-glass-effect-no exad-sticky-section-no\" data-id=\"297e9aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f2f869 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"2f2f869\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53dfd53 elementor-shape-rounded elementor-grid-0 e-grid-align-center exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-social-icons\" data-id=\"53dfd53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-67f6dfa\" href=\"https:\/\/www.facebook.com\/proselectint\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-a95c42f\" href=\"https:\/\/www.youtube.com\/watch?v=WurLv6TZZmg\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-4c3f770\" href=\"https:\/\/www.instagram.com\/proselectinternational\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3048e55 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-spacer\" data-id=\"3048e55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4321a0d8 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"4321a0d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Blogpost teilen:<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Heute ist Valentinstag \u2013 ein Tag, an dem wir die Liebe in all ihren Formen feiern. Bei PRO SELECT steht der Valentinstag nicht nur f\u00fcr Blumen und Pralinen, sondern f\u00fcr die wahren Liebesgeschichten, die uns in unserer Arbeit jeden Tag ber\u00fchren. Es sind Geschichten von Mut, Hoffnung und der unersch\u00fctterlichen Kraft der Liebe, die keine Grenzen kennt. <\/p>\n","protected":false},"author":7,"featured_media":7041,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"content-type":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[],"class_list":["post-7040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Liebe kennt keine Grenzen - Valentinstag bei PRO SELECT - Pro Select<\/title>\n<meta name=\"description\" content=\"Heute ist Valentinstag \u2013 ein Tag, an dem wir die Liebe in all ihren Formen feiern. Bei PRO SELECT steht der Valentinstag nicht nur f\u00fcr Blumen und Pralinen, sondern f\u00fcr die wahren Liebesgeschichten, die uns in unserer Arbeit jeden Tag ber\u00fchren. Es sind Geschichten von Mut, Hoffnung und der unersch\u00fctterlichen Kraft der Liebe, die keine Grenzen kennt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proselectint.com\/de_de\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liebe kennt keine Grenzen - Valentinstag bei PRO SELECT - Pro Select\" \/>\n<meta property=\"og:description\" content=\"Heute ist Valentinstag \u2013 ein Tag, an dem wir die Liebe in all ihren Formen feiern. Bei PRO SELECT steht der Valentinstag nicht nur f\u00fcr Blumen und Pralinen, sondern f\u00fcr die wahren Liebesgeschichten, die uns in unserer Arbeit jeden Tag ber\u00fchren. Es sind Geschichten von Mut, Hoffnung und der unersch\u00fctterlichen Kraft der Liebe, die keine Grenzen kennt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proselectint.com\/de_de\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/\" \/>\n<meta property=\"og:site_name\" content=\"Pro Select\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proselectint\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-13T23:07:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-03T13:22:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942.png\" \/>\n\t<meta property=\"og:image:width\" content=\"992\" \/>\n\t<meta property=\"og:image:height\" content=\"557\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Katerina Stojanovska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katerina Stojanovska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/\"},\"author\":{\"name\":\"Katerina Stojanovska\",\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/#\\\/schema\\\/person\\\/4840a08b475e1780ad4faecce1b50e25\"},\"headline\":\"Liebe kennt keine Grenzen &#8211; Valentinstag bei PRO SELECT\",\"datePublished\":\"2025-02-13T23:07:15+00:00\",\"dateModified\":\"2025-07-03T13:22:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/\"},\"wordCount\":540,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.proselectint.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Screenshot-2025-02-12-235942.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/\",\"url\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/\",\"name\":\"Liebe kennt keine Grenzen - Valentinstag bei PRO SELECT - Pro Select\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.proselectint.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Screenshot-2025-02-12-235942.png\",\"datePublished\":\"2025-02-13T23:07:15+00:00\",\"dateModified\":\"2025-07-03T13:22:09+00:00\",\"description\":\"Heute ist Valentinstag \u2013 ein Tag, an dem wir die Liebe in all ihren Formen feiern. Bei PRO SELECT steht der Valentinstag nicht nur f\u00fcr Blumen und Pralinen, sondern f\u00fcr die wahren Liebesgeschichten, die uns in unserer Arbeit jeden Tag ber\u00fchren. Es sind Geschichten von Mut, Hoffnung und der unersch\u00fctterlichen Kraft der Liebe, die keine Grenzen kennt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.proselectint.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Screenshot-2025-02-12-235942.png\",\"contentUrl\":\"https:\\\/\\\/www.proselectint.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Screenshot-2025-02-12-235942.png\",\"width\":992,\"height\":557},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.proselectint.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liebe kennt keine Grenzen &#8211; Valentinstag bei PRO SELECT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/#website\",\"url\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/\",\"name\":\"Pro Select\",\"description\":\"Internationale Personal- und Unternehmensberatung\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/#organization\",\"name\":\"Pro Select\",\"url\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.proselectint.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-pro-select.svg\",\"contentUrl\":\"https:\\\/\\\/www.proselectint.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-pro-select.svg\",\"width\":183,\"height\":84,\"caption\":\"Pro Select\"},\"image\":{\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proselectint\\\/\",\"https:\\\/\\\/www.instagram.com\\\/proselectinternational\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/#\\\/schema\\\/person\\\/4840a08b475e1780ad4faecce1b50e25\",\"name\":\"Katerina Stojanovska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4184f6c7e5172511d9c64702be07a097ab3f853e040feb28989264c16e8bfe27?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4184f6c7e5172511d9c64702be07a097ab3f853e040feb28989264c16e8bfe27?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4184f6c7e5172511d9c64702be07a097ab3f853e040feb28989264c16e8bfe27?s=96&d=mm&r=g\",\"caption\":\"Katerina Stojanovska\"},\"url\":\"https:\\\/\\\/www.proselectint.com\\\/de_de\\\/author\\\/katerina-stojanovska\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liebe kennt keine Grenzen - Valentinstag bei PRO SELECT - Pro Select","description":"Heute ist Valentinstag \u2013 ein Tag, an dem wir die Liebe in all ihren Formen feiern. Bei PRO SELECT steht der Valentinstag nicht nur f\u00fcr Blumen und Pralinen, sondern f\u00fcr die wahren Liebesgeschichten, die uns in unserer Arbeit jeden Tag ber\u00fchren. Es sind Geschichten von Mut, Hoffnung und der unersch\u00fctterlichen Kraft der Liebe, die keine Grenzen kennt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proselectint.com\/de_de\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/","og_locale":"de_DE","og_type":"article","og_title":"Liebe kennt keine Grenzen - Valentinstag bei PRO SELECT - Pro Select","og_description":"Heute ist Valentinstag \u2013 ein Tag, an dem wir die Liebe in all ihren Formen feiern. Bei PRO SELECT steht der Valentinstag nicht nur f\u00fcr Blumen und Pralinen, sondern f\u00fcr die wahren Liebesgeschichten, die uns in unserer Arbeit jeden Tag ber\u00fchren. Es sind Geschichten von Mut, Hoffnung und der unersch\u00fctterlichen Kraft der Liebe, die keine Grenzen kennt.","og_url":"https:\/\/www.proselectint.com\/de_de\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/","og_site_name":"Pro Select","article_publisher":"https:\/\/www.facebook.com\/proselectint\/","article_published_time":"2025-02-13T23:07:15+00:00","article_modified_time":"2025-07-03T13:22:09+00:00","og_image":[{"width":992,"height":557,"url":"https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942.png","type":"image\/png"}],"author":"Katerina Stojanovska","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Katerina Stojanovska","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/#article","isPartOf":{"@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/"},"author":{"name":"Katerina Stojanovska","@id":"https:\/\/www.proselectint.com\/de_de\/#\/schema\/person\/4840a08b475e1780ad4faecce1b50e25"},"headline":"Liebe kennt keine Grenzen &#8211; Valentinstag bei PRO SELECT","datePublished":"2025-02-13T23:07:15+00:00","dateModified":"2025-07-03T13:22:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/"},"wordCount":540,"commentCount":0,"publisher":{"@id":"https:\/\/www.proselectint.com\/de_de\/#organization"},"image":{"@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/#primaryimage"},"thumbnailUrl":"https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942.png","articleSection":["News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/","url":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/","name":"Liebe kennt keine Grenzen - Valentinstag bei PRO SELECT - Pro Select","isPartOf":{"@id":"https:\/\/www.proselectint.com\/de_de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/#primaryimage"},"image":{"@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/#primaryimage"},"thumbnailUrl":"https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942.png","datePublished":"2025-02-13T23:07:15+00:00","dateModified":"2025-07-03T13:22:09+00:00","description":"Heute ist Valentinstag \u2013 ein Tag, an dem wir die Liebe in all ihren Formen feiern. Bei PRO SELECT steht der Valentinstag nicht nur f\u00fcr Blumen und Pralinen, sondern f\u00fcr die wahren Liebesgeschichten, die uns in unserer Arbeit jeden Tag ber\u00fchren. Es sind Geschichten von Mut, Hoffnung und der unersch\u00fctterlichen Kraft der Liebe, die keine Grenzen kennt.","breadcrumb":{"@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/#primaryimage","url":"https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942.png","contentUrl":"https:\/\/www.proselectint.com\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-12-235942.png","width":992,"height":557},{"@type":"BreadcrumbList","@id":"https:\/\/www.proselectint.com\/pro-select-liebe-kennt-keine-grenzen-valentingstag-bei-proselect\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.proselectint.com\/"},{"@type":"ListItem","position":2,"name":"Liebe kennt keine Grenzen &#8211; Valentinstag bei PRO SELECT"}]},{"@type":"WebSite","@id":"https:\/\/www.proselectint.com\/de_de\/#website","url":"https:\/\/www.proselectint.com\/de_de\/","name":"Pro Select","description":"Internationale Personal- und Unternehmensberatung","publisher":{"@id":"https:\/\/www.proselectint.com\/de_de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proselectint.com\/de_de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.proselectint.com\/de_de\/#organization","name":"Pro Select","url":"https:\/\/www.proselectint.com\/de_de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.proselectint.com\/de_de\/#\/schema\/logo\/image\/","url":"https:\/\/www.proselectint.com\/wp-content\/uploads\/2021\/07\/logo-pro-select.svg","contentUrl":"https:\/\/www.proselectint.com\/wp-content\/uploads\/2021\/07\/logo-pro-select.svg","width":183,"height":84,"caption":"Pro Select"},"image":{"@id":"https:\/\/www.proselectint.com\/de_de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proselectint\/","https:\/\/www.instagram.com\/proselectinternational\/"]},{"@type":"Person","@id":"https:\/\/www.proselectint.com\/de_de\/#\/schema\/person\/4840a08b475e1780ad4faecce1b50e25","name":"Katerina Stojanovska","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4184f6c7e5172511d9c64702be07a097ab3f853e040feb28989264c16e8bfe27?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4184f6c7e5172511d9c64702be07a097ab3f853e040feb28989264c16e8bfe27?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4184f6c7e5172511d9c64702be07a097ab3f853e040feb28989264c16e8bfe27?s=96&d=mm&r=g","caption":"Katerina Stojanovska"},"url":"https:\/\/www.proselectint.com\/de_de\/author\/katerina-stojanovska\/"}]}},"_links":{"self":[{"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/posts\/7040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/comments?post=7040"}],"version-history":[{"count":7,"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/posts\/7040\/revisions"}],"predecessor-version":[{"id":7050,"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/posts\/7040\/revisions\/7050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/media\/7041"}],"wp:attachment":[{"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/media?parent=7040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/categories?post=7040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proselectint.com\/de_de\/wp-json\/wp\/v2\/tags?post=7040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}